{"id":1355,"date":"2008-12-05T12:53:44","date_gmt":"2008-12-05T11:53:44","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/?p=1355"},"modified":"2008-12-05T16:40:19","modified_gmt":"2008-12-05T15:40:19","slug":"knatte-fnatte-och-tjatte","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2008\/12\/05\/knatte-fnatte-och-tjatte\/","title":{"rendered":"Knatte, Fnatte och Tjatte"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:648,&quot;href&quot;:&quot;http:\\\/\\\/www.duckipedia.de\\\/index.php&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.duckipedia.de\\\/index.php&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:649,&quot;href&quot;:&quot;http:\\\/\\\/www.duckipedia.de\\\/index.php\\\/Tick%2C_Trick_und_Track&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20241203203830\\\/https:\\\/\\\/www.duckipedia.de\\\/index.php\\\/Tick%2C_Trick_und_Track&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-11 12:42:26&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-11 12:42:26&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p>F\u00fcr eine l\u00e4ngere Zugfahrt habe ich mir neulich eine &#8220;Lustiges Taschenbuch&#8221; gekauft, also ein dickes Comicheft mit Geschichten aus Entenhausen. Fr\u00fcher, als ich noch im Westen lebte und nur halb so gro\u00df war wie jetzt, geh\u00f6rten die B\u00fccher selbstverst\u00e4ndlich zur Pflichtlekt\u00fcre. Bemerkenswert an den Geschichten war, dass nur jede zweite Seite farbig bedruckt war. So sorgten damals nicht nur die fesselnden Storys, sondern auch die regelm\u00e4\u00dfigen Wechsel zwischen schwarz-wei\u00dfen und bunten Comic-Bildern f\u00fcr Spannung. Diejenigen, die versuchten, die monochromen Seiten auf eigene Faust nachzucolorieren geh\u00f6rten allerdings zu den Ge\u00e4chteten, denn das Papier war derart d\u00fcnn, dass Farbstriche durchschimmerten.<\/p>\n<p>Schon damals dachte ich: Ach, es m\u00fcsste ein Lexikon \u00fcber das Entenhausen-Universum geben. Irgendwann gabs das, glaube ich, auch mal in gedruckter Form als Nachschlagewerk. Aber es geht noch besser: Als online-Lexikon wie wikipedia, nur unter anderem Namen: <a href=\"http:\/\/www.duckipedia.de\/index.php\/\">Duckipedia<\/a>. Dort gibt es schon gut 3000 Artikel \u00fcber die Ducks, Mickey, Goofy, ihre Abenteuer, Hintergr\u00fcnde und Autoren. Und dort erf\u00e4hrt man dann auch, wie <a title=\"Duckipedia \u00fcber Tick, Trick und Track\" href=\"http:\/\/www.duckipedia.de\/index.php\/Tick%2C_Trick_und_Track\">Tick, Trick und Track<\/a>, Donalds clevere Neffen, in unterschiedlichen \u00dcbersetzungen hei\u00dfen. Eine Auswahl:<\/p>\n<li>D\u00e4nisch: Rip, Rap og Rup<\/li>\n<li>Englisch: Huey, Dewey and Louie<\/li>\n<li>Finnisch: Tupu, Hupu ja Lupu<\/li>\n<li>Franz\u00f6sisch: Riri, Fifi et Loulou<\/li>\n<li>Niederl\u00e4ndisch: Kwik, Kwek en Kwak<\/li>\n<li>Norwegisch: Ole, Dole og Doffen<\/li>\n<li>Portugiesisch: Huguinho, Zezinho e Luizinho<\/li>\n<li>Schwedisch: Knatte, Fnatte och Tjatte<\/li>\n<li>T\u00fcrkisch: Cin, Can ve Cem<\/li>\n<p>Die schwedische Variante gef\u00e4llt mir am besten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr eine l\u00e4ngere Zugfahrt habe ich mir neulich eine &#8220;Lustiges Taschenbuch&#8221; gekauft, also ein dickes Comicheft mit Geschichten aus Entenhausen. Fr\u00fcher, als ich noch im Westen lebte und nur halb so gro\u00df war wie jetzt, geh\u00f6rten die B\u00fccher selbstverst\u00e4ndlich zur Pflichtlekt\u00fcre. Bemerkenswert an den Geschichten war, dass nur jede zweite Seite farbig bedruckt war. So &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2008\/12\/05\/knatte-fnatte-och-tjatte\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eKnatte, Fnatte och Tjatte\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[619,637,584],"class_list":["post-1355","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-comic","tag-internet","tag-lexikon"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-lR","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/1355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=1355"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/1355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=1355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=1355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=1355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}