{"id":151,"date":"2006-03-12T21:04:53","date_gmt":"2006-03-12T20:04:53","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/?p=151"},"modified":"2006-08-04T18:07:00","modified_gmt":"2006-08-04T16:07:00","slug":"open-source-triumph","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2006\/03\/12\/open-source-triumph\/","title":{"rendered":"Open-Source-Triumph"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[]'><\/div>\n<p>Herrn Christian Kohlhof ist es an diesem Abend eine besondere Ehre, der Welt\u00f6ffentlichkeit dar\u00fcber Mitteilung zu machen, dass er in diesem Moment zum ersten Mal mit seiner eigenen Linux-Installation online ist. Es hat auch nur knapp vier Monate, ein Handbuch, eine Fachzeitschrift, ein Gespr\u00e4ch mit einem Linux-Fachmann und schlie\u00dflich ein Netzwerkkabel gebraucht, um darauf zu verzichten, \u00fcbers W-Lan mit\u00a0 dem Internet Verbindung aufzunehmen. Stattdessen habe ich also ein Ethernetkabel aus dem Keller geholt und Rechner und Router verbunden.<\/p>\n<p>Es ist die ein Triumph eines vernunftbegabten Individuums \u00fcber seelenlose Technik. Ich m\u00f6chte schlicht herausfinden, ob das Open-Source-Betriebssystem wirklich eine Alternative zum kommerziellen Windows ist und ob ich es verstehe. Ich habe schlie\u00dflich nur aus meinem Selbsterhaltungstrieb heraus meinen k\u00fchnen Plan aufgegeben, per drahtloser Kommunikation mit Liunx ins Internet zu klicken. Aber mit diesem Kompromiss lebe ich gerne.<\/p>\n<p>Die ersten Linux Erfahrungen machen michnat\u00fcrlich\u00a0 skeptisch, aber Suse-Linux bekommt noch mehrere faire Chancen. Das Rumfummeln am Linux-Rechner erinnert mich zudem an die ersten Gehversuche mit Windows 3.11 und dergleichen. Mir kommt das alles n\u00e4mlich noch ein bisschen un\u00fcbersichtlich vor.<\/p>\n<p>Dabei werben die Linux-Vertriebe derzeit damit, dass mit ihrem Betriebssystem alles so einfach zu installieren und zu konfigurieren ist wie bei Windows XP (das mittlerweile ja tats\u00e4chlich pflegeleicht ist, wenn man die n\u00f6tigen Schutzvorkehrungen wie Firewall und automatisches Update regelm\u00e4\u00dfig einsetzt). Na ja, zumindest was die W-Lan-Konfiguration angeht, verzichte ich auf Euphorie. Aber Open Office und dergleichen, die zum Paket dazugeh\u00f6ren, sind nat\u00fcrlich ein Pfund, mit dem Linux wuchern kann. Schlie\u00dflich l\u00e4uft die Distribution von Suse ansonsten augenscheinlich fehlerfrei und reibungslos.\n<\/p>\n<p>Sch\u00f6nen Abend noch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Herrn Christian Kohlhof ist es an diesem Abend eine besondere Ehre, der Welt\u00f6ffentlichkeit dar\u00fcber Mitteilung zu machen, dass er in diesem Moment zum ersten Mal mit seiner eigenen Linux-Installation online ist. Es hat auch nur knapp vier Monate, ein Handbuch, eine Fachzeitschrift, ein Gespr\u00e4ch mit einem Linux-Fachmann und schlie\u00dflich ein Netzwerkkabel gebraucht, um darauf zu &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2006\/03\/12\/open-source-triumph\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eOpen-Source-Triumph\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[639],"class_list":["post-151","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-computer"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-2r","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}