{"id":2370,"date":"2009-10-12T18:32:30","date_gmt":"2009-10-12T16:32:30","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/?p=2370"},"modified":"2009-10-13T15:59:09","modified_gmt":"2009-10-13T13:59:09","slug":"sofort-ausfullen","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2009\/10\/12\/sofort-ausfullen\/","title":{"rendered":"Sofort Ausfullen!"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:463,&quot;href&quot;:&quot;http:\\\/\\\/www.ndr1radiomv.de\\\/programm\\\/stcomputer100.html&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.ndr.de:443\\\/radiomv&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:464,&quot;href&quot;:&quot;http:\\\/\\\/www.radiomv.de&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.ndr.de:443\\\/radiomv&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p>Grob \u00fcberschlagen habe ich in den vergangenen drei Monaten wohl an die 24 Millionen Euro gewonnen. Allein durch Gewinnspiele rund um die Fu\u00dfball-WM im kommenden Jahr, durch ungl\u00fcckliche Todesf\u00e4lle einsamer Deutscher in Nigeria oder durch Internetlotterien mit sensationellen Gewinnquoten &#8211; jedenfalls w\u00fcrde mir dieser Batzen Geld geh\u00f6ren, wenn die vielen Spamnachrichten denn wahr w\u00e4ren, die jede Woche in meinen Mail-Postf\u00e4chern landen. Diese Angaben in diesen Nachrichten sind aber nat\u00fcrlich nicht wahr &#8211; das sieht man auf den ersten Blick. Und wenn nicht: Vielleicht wirds ja beim H\u00f6ren deutlich. Bedienen Sie sich zu diesem Zweck bitte des angeh\u00e4ngten Podcasts.<\/p>\n<p>[display_podcast]<\/p>\n<p>Schutz vor Spam und Viren, vor Betrug und b\u00f6sen Buben im Internet, das ist am Dienstag auch das Thema beim <a title=\"Servicetag &quot;Computer und Internet&quot; auf NDR1 Radio MV\" href=\"http:\/\/www.ndr1radiomv.de\/programm\/stcomputer100.html\">Service-Tag auf NDR1 Radio MV<\/a>. Von 8 bis 13 Uhr stehen drei Fachleute im Studio Rede und Antwort:<\/p>\n<p>Rechtsanwalt Johannes Richard aus Rostock hat sich auf Streitf\u00e4lle rund um Internetseiten und Online-Angebote spezialisiert.<\/p>\n<p>J\u00f6rg Otto Czimczik vom Landeshochschulverband wird unter anderem Tipps geben, welche Computer-Programme wirklich n\u00fctzlich sind und wie Anwender Sicherheitskopien von ihren Daten anlegen k\u00f6nnen.<\/p>\n<p>Axel Friedrich vom Schweriner Systemhaus Planet-IC GmbH ist beim Servicetag unter anderem der Fachmann f\u00fcr den Schutz vor Viren und anderen Bedrohungen aus dem Internet.<\/p>\n<p>Kostenlose Hotline zu <a title=\"Link zu NDR1 Radio MV - Startseite\" href=\"http:\/\/www.radiomv.de\">NDR1 Radio MV<\/a>: 0800\/59 59 &#8211; 100.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grob \u00fcberschlagen habe ich in den vergangenen drei Monaten wohl an die 24 Millionen Euro gewonnen. Allein durch Gewinnspiele rund um die Fu\u00dfball-WM im kommenden Jahr, durch ungl\u00fcckliche Todesf\u00e4lle einsamer Deutscher in Nigeria oder durch Internetlotterien mit sensationellen Gewinnquoten &#8211; jedenfalls w\u00fcrde mir dieser Batzen Geld geh\u00f6ren, wenn die vielen Spamnachrichten denn wahr w\u00e4ren, die &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2009\/10\/12\/sofort-ausfullen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eSofort Ausfullen!\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10],"tags":[660,639,637,105,168,1022,43],"class_list":["post-2370","post","type-post","status-publish","format-standard","hentry","category-anhoren","tag-beratung","tag-computer","tag-internet","tag-kriminalitat","tag-podcast","tag-arbeit","tag-spam"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-Ce","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/2370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=2370"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/2370\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=2370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=2370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=2370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}