{"id":334,"date":"2006-08-04T12:50:31","date_gmt":"2006-08-04T10:50:31","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/?p=334"},"modified":"2006-08-04T12:50:31","modified_gmt":"2006-08-04T10:50:31","slug":"die-beste-entscheidung-des-tages","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2006\/08\/04\/die-beste-entscheidung-des-tages\/","title":{"rendered":"Die beste Entscheidung des Tages"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[]'><\/div>\n<p>\u00dcber Rostock geht gerade ein Wolkenbruch hernieder mit allem, was dazu geh\u00f6rt. Also rei\u00dfenden B\u00e4chen auf Stra\u00dfen und Fu\u00dfwegen, Blitz und grimmigem Donner. Der erste richtige Regen seit Wochen. In diesem Zusammenhang m\u00f6chte ich mir deshalb aber nun selbst gratulieren: F\u00fcr die weise Entscheidung n\u00e4mlich, vorhin auf dem R\u00fcckweg vom Termin zum Studio noch kurz zu Hause vorbeizufahren und die weit ge\u00f6ffnete Dachluke zu schlie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber Rostock geht gerade ein Wolkenbruch hernieder mit allem, was dazu geh\u00f6rt. Also rei\u00dfenden B\u00e4chen auf Stra\u00dfen und Fu\u00dfwegen, Blitz und grimmigem Donner. Der erste richtige Regen seit Wochen. In diesem Zusammenhang m\u00f6chte ich mir deshalb aber nun selbst gratulieren: F\u00fcr die weise Entscheidung n\u00e4mlich, vorhin auf dem R\u00fcckweg vom Termin zum Studio noch kurz &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2006\/08\/04\/die-beste-entscheidung-des-tages\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDie beste Entscheidung des Tages\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[69,636,646],"class_list":["post-334","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-gewitter","tag-tagebuch","tag-wetter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-5o","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}