{"id":347,"date":"2006-08-11T02:00:21","date_gmt":"2006-08-11T00:00:21","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/?p=347"},"modified":"2006-08-11T02:02:42","modified_gmt":"2006-08-11T00:02:42","slug":"akustisch-ungewohnliche-premiere","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2006\/08\/11\/akustisch-ungewohnliche-premiere\/","title":{"rendered":"Akustisch ungew\u00f6hnliche Premiere"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[]'><\/div>\n<p><strong>Rostock hat am ersten Abend der Hansesail 2006 eine Weltpremiere erlebt. 60 Musiker spielten an Schiffssirenen, Kirchenglocken, Blechblasinstrumenten in Mastk\u00f6rben und auf Trommeln die Hafensinfonie, die extra f\u00fcr dieses gro\u00dfe maritime Volksfest komponiert wurde. Die tausenden Zuh\u00f6rer staunten nicht schlecht \u00fcber die ungew\u00f6hnlichen Kl\u00e4nge, die \u00fcber den Stadthafen schallten &#8211; f\u00fcr viele war das Gehupe und Getrommel wohl doch \u00e4u\u00dferst ungew\u00f6hnlich.<\/strong><\/p>\n<p>Hier mal ein paar Ausschnitte, aufgenommen mit meinem Telefon, deswegen die miserable technische Qualit\u00e4t.<\/p>\n[audio:hafensinfonie06.mp3]\n<p>Knapp 20 Minuten lang waren die Signalh\u00f6rner von f\u00fcnf oder sechs Schiffen, das Getrommel auf der B\u00fchne und die kurzen EInw\u00fcrfe der Posaunisten, die tats\u00e4chlich irgendwo ganz oben auf den Schiffsmasten sa\u00dfen, zu h\u00f6ren. Die Glocken von vier Rostocker Kirchen rund um den Stadthafen allerdings waren zumindest auf der Haedge-Halbinsel nicht zu h\u00f6ren.<\/p>\n<p>Die Schwierigkeit bei Musikdarbietungen dieser Art ist die Koordination der Takte: Die hunderte Meter von einander entfernten Musiker m\u00fcssen nicht nur die gleiche Geschwindigkeit beim Spielen und Mitz\u00e4hlen einhalten, sie m\u00fcssen auch bedenken, dass der Schall \u00fcber derart gro\u00dfe Distanzen schon eine Weile unterwegs ist. Aus diesem Grund klang die gesamte Sinfonie zuweilen etwas holperig, was durch das Dr\u00f6hnen der Typhone, die sowieso nicht aufeinander abgestimmt sind, noch verst\u00e4rkt wurde. Beeindruckend ist aber, dass die Musiker, die \u00fcber Funk miteinander verbunden waren und sich zudem alle nach einem monotonen Grundschlag der Percussion richteten, zeitweise verh\u00e4ltnism\u00e4\u00dfig pr\u00e4zise einen Dialog zwischen ihren&#8221;Instrumenten&#8221; erreichten.<\/p>\n<p>Das erinnert mich \u00fcbrigens an ein \u00e4hnliches Konzert mit den L\u00fcbecker Innenstadtkirchen. Ein Komponist aus Spanien hatte ein Musikst\u00fcck komponiert, bei dem die Glocken von sieben Kirchen ein Instrument bildeten. Das war 1992 &#8211; Sch\u00fcler waren damals als Musiker engagiert. Ich stand auf dem Turm des Domes. Das St\u00fcck hie\u00df &#8220;Concordia Domi Foris Pax&#8221;. Wies geklungen hat? Keine Ahnung. Wir waren viel zu sehr damit besch\u00e4ftigt, die Musik genau nach Zeitplan, mit Stoppuhr, \u00fcber die B\u00fchne zu bringen&#8230;\n<\/p>\n<p>Aber es war wohl in etwa so wie jetzt in Rostock: Leicht ins Ohr ging die Hafen-Sinfonie trotz allem Bem\u00fchens nicht, sie erinnerte eher an eine Mischung aus ganz seltsamem Freestyle-Jazz und preu\u00dfischem Samba. Aber unterm Strich: Das Gestampfe der Trommeln, der L\u00e4rm der Schiffe, das Gekreische der Posaunen, das weckt die Vermutung, wie es fr\u00fcher wohl in einem Hafen wie Rostock geklungen haben muss, wenn Dampfmaschinen auf den Werften arbeiteten, Schlepper tuckerten, Schiffe einliefen und M\u00f6wen sich um die Reste eines Fischfangs stritten.<\/p>\n<p>Mit ein bisschen Phantasie war die Komposition, oder auch das Arrangement von Wolfgang Schmiedt von der HMT doch ganz gut anzuh\u00f6ren&#8230;<\/p>\n<p>Zum Ausgleich nun trotzdem noch ein paar harmlose Abendimpressionen von der Festmeile<\/p>\n<p><img decoding=\"async\" alt=\"Schiffsmasten im Nachthimmel\" src=\"https:\/\/www.kohlhof.de\/kohlhof\/wp-content\/uploads\/2006\/08\/sail06do1.jpg\" \/><\/p>\n<p class=\"bu\">Die Masten der Vollschiffe ragen in den Nachthimmel.<\/p>\n<p><img decoding=\"async\" alt=\"Riesenrad auf der Haedgehalbinsel\" src=\"https:\/\/www.kohlhof.de\/kohlhof\/wp-content\/uploads\/2006\/08\/sail06do2.jpg\" \/><\/p>\n<p class=\"bu\">Das Riesenrad auf der Haedgehalbinsel steht zwischen dem historischen Br\u00fcckenkran und dem Schnellboot Ozelot<\/p>\n<p><img decoding=\"async\" alt=\"Kassenschild\" src=\"https:\/\/www.kohlhof.de\/kohlhof\/wp-content\/uploads\/2006\/08\/sail06do3.jpg\" \/><\/p>\n<p><\/p>\n<p class=\"bu\">Das wohl sch\u00f6nste Kassen-Leuschtschild geh\u00f6rt &#8230;<\/p>\n<p><\/p>\n<p><img decoding=\"async\" alt=\"Fahrgesch\u00e4ft bei Nacht\" src=\"https:\/\/www.kohlhof.de\/kohlhof\/wp-content\/uploads\/2006\/08\/sail06do4.jpg\" \/><\/p>\n<p class=\"bu\">&#8230; zu dieser Krawallbude.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rostock hat am ersten Abend der Hansesail 2006 eine Weltpremiere erlebt. 60 Musiker spielten an Schiffssirenen, Kirchenglocken, Blechblasinstrumenten in Mastk\u00f6rben und auf Trommeln die Hafensinfonie, die extra f\u00fcr dieses gro\u00dfe maritime Volksfest komponiert wurde. Die tausenden Zuh\u00f6rer staunten nicht schlecht \u00fcber die ungew\u00f6hnlichen Kl\u00e4nge, die \u00fcber den Stadthafen schallten &#8211; f\u00fcr viele war das Gehupe &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2006\/08\/11\/akustisch-ungewohnliche-premiere\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eAkustisch ungew\u00f6hnliche Premiere\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[22,61,19],"class_list":["post-347","post","type-post","status-publish","format-standard","hentry","category-musik-des-tages","tag-hansesail","tag-musik","tag-rostock"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-5B","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/347\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}