{"id":873,"date":"2008-06-26T01:01:06","date_gmt":"2008-06-25T23:01:06","guid":{"rendered":"http:\/\/www.kohlhof.de\/kohlhof\/2008\/06\/26\/ligo-ohne-regen\/"},"modified":"2008-06-30T08:49:09","modified_gmt":"2008-06-30T06:49:09","slug":"ligo-ohne-regen","status":"publish","type":"post","link":"https:\/\/www.kohlhof.de\/kohlhof\/2008\/06\/26\/ligo-ohne-regen\/","title":{"rendered":"Ligo ohne Regen"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:796,&quot;href&quot;:&quot;http:\\\/\\\/www.flickr.com\\\/photos\\\/14841335@N08\\\/2621603294&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.flickr.com\\\/photos\\\/14841335@N08\\\/2621603294&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:786,&quot;href&quot;:&quot;http:\\\/\\\/www.flickr.com\\\/photos\\\/14841335@N08\\\/2621603718&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20260211152647\\\/https:\\\/\\\/www.flickr.com\\\/photos\\\/14841335@N08\\\/2621603718&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.flickr.com\\\/photos\\\/14841335@N08\\\/2621603718&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-23 20:35:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-27 22:34:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-04 08:00:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-14 18:13:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 16:46:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-14 19:11:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-21 21:16:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-28 03:25:26&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-05 03:25:34&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-05 03:25:34&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p>Soeben komme ich von einem sehr sch\u00f6nen Kurzurlaub nach Lettland zur\u00fcck. Dort wird Ende Juni das Ligo-Fest gefeiert, das ohne Pause ins Janis-Fest \u00fcbergeht. Freundschaften aus Studienzeiten haben daf\u00fcr gesorgt, dass ich bei dieser bunten, fr\u00f6hlichen, n\u00e4chtelangen Feierei in diesem Jahr dabei sein durfte &#8211; und gleichzeitig Lettland sozusagen backstage kennenlernen konnte.<\/p>\n<p><a href=\"http:\/\/www.flickr.com\/photos\/14841335@N08\/2621603294\/\" title=\"IMG_4033 von Lord Roetel bei Flickr\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" src=\"http:\/\/farm4.static.flickr.com\/3216\/2621603294_1c036f4d41.jpg\" alt=\"IMG_4033\" height=\"334\" \/><\/a><\/p>\n<blockquote><p><em>Stimmungsvolle Mittsommernacht. Die kleine H\u00fctte mit dem warmen Licht im Innern und dem Apfelbaum vor der T\u00fcr war unsere Sauna. An jenem Abend ging es noch ruhig zu &#8211; ein Tag sp\u00e4ter war alles voller feiernder Letten. Dazu sp\u00e4ter mehr<\/em>.<\/p><\/blockquote>\n<p>Man sah mich unter anderem Eichenlaub- umkr\u00e4nzt <!--more-->durch den Festsaal h\u00fcpfen und schon wenig sp\u00e4ter aus der Sauna direkt in den angrenzenden Teich springen, gemeinsam mit 40 fr\u00f6hlichen Lettinnen und Letten &#8211; ein bemerkenswertes Fest, von dem ich gern mehr berichten m\u00f6chte&#8230; aber nicht mehr heute. Morgen ist Fr\u00fchdienst angesagt. Und wenn ich den \u00fcberstanden habe, werde ich hier einen Reisebericht ver\u00f6ffentlichen.<\/p>\n<p><a href=\"http:\/\/www.flickr.com\/photos\/14841335@N08\/2621603718\/\" title=\"IMG_4234 von Lord Roetel bei Flickr\"><img loading=\"lazy\" decoding=\"async\" width=\"334\" src=\"http:\/\/farm4.static.flickr.com\/3025\/2621603718_3731f172f6.jpg\" alt=\"IMG_4234\" height=\"500\" \/><\/a><\/p>\n<blockquote><p><em>Auch dieser Bottich trug dazu bei, dass man im besten Sinn von einer sensationellen Sause 30 Kilometer vor der Grenze zu Wei\u00dfrussland sprechen kann<\/em>.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Soeben komme ich von einem sehr sch\u00f6nen Kurzurlaub nach Lettland zur\u00fcck. Dort wird Ende Juni das Ligo-Fest gefeiert, das ohne Pause ins Janis-Fest \u00fcbergeht. Freundschaften aus Studienzeiten haben daf\u00fcr gesorgt, dass ich bei dieser bunten, fr\u00f6hlichen, n\u00e4chtelangen Feierei in diesem Jahr dabei sein durfte &#8211; und gleichzeitig Lettland sozusagen backstage kennenlernen konnte. Stimmungsvolle Mittsommernacht. Die &hellip; <a href=\"https:\/\/www.kohlhof.de\/kohlhof\/2008\/06\/26\/ligo-ohne-regen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eLigo ohne Regen\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[424,418,183,422,417,421,348],"class_list":["post-873","post","type-post","status-publish","format-standard","hentry","category-politik-und-verwaltung","tag-baltikum","tag-fest","tag-fotos","tag-janis","tag-lettland","tag-ligo","tag-urlaub"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paimI-e5","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/comments?post=873"}],"version-history":[{"count":0,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/posts\/873\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/media?parent=873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/categories?post=873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kohlhof.de\/kohlhof\/wp-json\/wp\/v2\/tags?post=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}